{"id":40,"count":2,"description":"","link":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/tag\/linkspartei\/","name":"Linkspartei","slug":"linkspartei","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/tags\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/posts?tags=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}