{"id":1635,"date":"2016-03-23T13:08:14","date_gmt":"2016-03-23T11:08:14","guid":{"rendered":"http:\/\/blogs.piratech.de\/piraten-kreuzhain\/?p=1635"},"modified":"2016-03-23T13:23:49","modified_gmt":"2016-03-23T11:23:49","slug":"die-wahlkampfplanung-nimmt-fahrt-auf","status":"publish","type":"post","link":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/2016\/03\/23\/die-wahlkampfplanung-nimmt-fahrt-auf\/","title":{"rendered":"Die Wahlkampfplanung nimmt Fahrt auf"},"content":{"rendered":"<pre>Die Landesliste und die Bezirksliste der Piratenpartei sind aufgestellt.\r\n2011 hatten wir die Agenda Xhain [<a class=\"moz-txt-link-freetext\" href=\"https:\/\/wiki.piratenpartei.de\/BE:Friedrichshain-Kreuzberg\/AgendaXhain\">https:\/\/wiki.piratenpartei.de\/BE:Friedrichshain-Kreuzberg\/AgendaXhain<\/a>] aufgestellt. Im R\u00fcckblick darauf haben wir \u00fcberrascht festgestellt, dass wir in der Tat das meiste davon umgesetzt oder in die Wege geleitet haben, und das als Oppositionsfraktion!\r\n\r\nWir sind nun flei\u00dfig dabei, unser Bezirksprogramm f\u00fcr die Wahl 2016 zu vervollst\u00e4ndigen. Wesentlich ist dabei die Stadtplanung, denn leider ist gr\u00fcne Baupolitik Betonpolitik, und die Transparenz des gr\u00fcnen Baustadtrates Hans Panhoff ist mit der Transparenz von Beton zu vergleichen. Daher hat die BVV auch die Amtsf\u00fchrung dieses Stadtrats missbilligt, der wesentliche Informationen mehrere Monate lang der BVV und den zust\u00e4ndigen Aussch\u00fcssen vorenthalten hatte. Die Gr\u00fcnen sahen darin wohl kein Problem und haben ihn gest\u00fctzt (wir sind ja gespannt, ob sie ihn wieder aufstellen).\r\n\r\nF\u00fcr den Wahlkampf arbeiten wir gerade an unserer Kampagne und dem Design der Plakate. Diese sind schon \u00fcber unseren Twitteraccount @prt_xhn verbreitet worden und werden auch demn\u00e4chst auf Fl\u00e4chen der Kulturplakatierung Berlin, die uns diese zur Verf\u00fcgung stellt, zu sehen sein. Bei den Plakaten gehen wir weg vom traditionellen orange und versprechen auch, keine nautischen Metaphern zu verwenden! Die Plakate werden erg\u00e4nzt durch Postkarten, die wir auslegen.\r\n\r\nDie Piraten Xhain treten ein f\u00fcr eine progressive und vorw\u00e4rtsgewandte Politik in allen Politikfeldern. Dabei ist f\u00fcr uns der Aspekt der Teilhabe zentral.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Die Landesliste und die Bezirksliste der Piratenpartei sind aufgestellt. 2011 hatten wir die Agenda Xhain [https:\/\/wiki.piratenpartei.de\/BE:Friedrichshain-Kreuzberg\/AgendaXhain] aufgestellt. Im R\u00fcckblick darauf haben wir \u00fcberrascht festgestellt, dass wir in der Tat das meiste davon umgesetzt oder in die Wege geleitet haben, und das als Oppositionsfraktion! Wir sind nun flei\u00dfig dabei, unser Bezirksprogramm f\u00fcr die Wahl 2016 zu <a href=\"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/2016\/03\/23\/die-wahlkampfplanung-nimmt-fahrt-auf\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153],"tags":[],"class_list":["post-1635","post","type-post","status-publish","format-standard","hentry","category-agh-wahl-2016"],"_links":{"self":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/posts\/1635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/comments?post=1635"}],"version-history":[{"count":5,"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/posts\/1635\/revisions"}],"predecessor-version":[{"id":1640,"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/posts\/1635\/revisions\/1640"}],"wp:attachment":[{"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/media?parent=1635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/categories?post=1635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.piratech.de\/friedrichshain-kreuzberg\/wp-json\/wp\/v2\/tags?post=1635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}